{"id":363,"date":"2026-04-23T13:31:32","date_gmt":"2026-04-23T13:31:32","guid":{"rendered":"http:\/\/northsound.es\/index.php\/inicio\/"},"modified":"2026-05-07T17:22:24","modified_gmt":"2026-05-07T17:22:24","slug":"inicio","status":"publish","type":"page","link":"https:\/\/northsound.es\/en\/","title":{"rendered":"Home"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong><span style=\"color: #fd7933; font-size: 16px;\">HOLDING \u00b7 VALENCIA \u00b7 NETHERLANDS<\/span><\/strong>[\/vc_column_text][nectar_highlighted_text color_type=&#8221;regular&#8221; style=&#8221;full_text&#8221; highlight_expansion=&#8221;default&#8221; text_direction=&#8221;default&#8221;]\n<h1>We build <span style=\"color: #f0552a;\">businesses<\/span> that grow well.<\/h1>\n[\/nectar_highlighted_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]North Sound SL is a family holding company and management firm specializing in the creation, development and operation of businesses with a solid, efficient and scalable foundation.[\/vc_column_text][\/vc_column][vc_column column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;bononesheader&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_cta btn_style=&#8221;curved-arrow-animation&#8221; heading_tag=&#8221;p&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;extra-color-gradient-1&#8243; text_color=&#8221;#FFFFFF&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;What we do&#8221; padding_top=&#8221;15px&#8221; padding_bottom=&#8221;15px&#8221; padding_left=&#8221;30px&#8221; padding_right=&#8221;30px&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30px&#8221;][nectar_cta btn_style=&#8221;curved-arrow-animation&#8221; heading_tag=&#8221;p&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; text_color=&#8221;#000000&#8243; button_border_color=&#8221;#000000&#8243; button_border_thickness=&#8221;1px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;Let&#039;s talk&#8221; padding_top=&#8221;15px&#8221; padding_bottom=&#8221;15px&#8221; padding_left=&#8221;30px&#8221; padding_right=&#8221;30px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;10%&#8221; bottom_padding=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;hidden&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; zindex=&#8221;100&#8243; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;parallax&#8221; animation_movement_type=&#8221;transform_x&#8221; column_parallax_intensity=&#8221;3.5&#8243; persist_movement_on_mobile=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_scrolling_text scroll_direction=&#8221;ltr&#8221; scroll_speed=&#8221;slower&#8221; text_color=&#8221;#0a0a0a&#8221; text_repeat_number=&#8221;5&#8243; text_repeat_divider=&#8221;none&#8221; style=&#8221;text_outline&#8221; outline_thickness=&#8221;thin&#8221; outline_applies_to=&#8221;text_only&#8221; overflow=&#8221;visible&#8221; background_image_animation=&#8221;None&#8221; custom_font_size=&#8221;2.5vw&#8221; custom_font_size_mobile=&#8221;2.5vw&#8221;]<strong>Concierge <span style=\"color: #f0552a;\">\u25cf<\/span> Media <span style=\"color: #f0552a;\">\u25cf<\/span> Retail <span style=\"color: #f0552a;\">\u25cf <\/span>Training <span style=\"color: #f0552a;\">\u25cf<\/span> Hospitality <span style=\"color: #f0552a;\">\u25cf<\/span> Communication <span style=\"color: #f0552a;\">\u25cf<\/span> <\/strong>[\/nectar_scrolling_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][milestone heading_inherit=&#8221;default&#8221; subject_padding=&#8221;2%&#8221; color=&#8221;Accent-Color&#8221; effect=&#8221;count&#8221; milestone_alignment=&#8221;default&#8221; number=&#8221;6&#8243; subject=&#8221;Active companies&#8221; number_font_size=&#8221;120&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][milestone heading_inherit=&#8221;default&#8221; subject_padding=&#8221;2%&#8221; color=&#8221;Accent-Color&#8221; effect=&#8221;count&#8221; milestone_alignment=&#8221;default&#8221; number=&#8221;2&#8243; subject=&#8221;MARKETS: ES &amp; NL&#8221; number_font_size=&#8221;120&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][milestone heading_inherit=&#8221;default&#8221; symbol_position=&#8221;after&#8221; subject_padding=&#8221;2%&#8221; color=&#8221;Accent-Color&#8221; effect=&#8221;count&#8221; symbol_alignment=&#8221;Superscript&#8221; milestone_alignment=&#8221;default&#8221; number=&#8221;4&#8243; subject=&#8221;KEY SECTORS&#8221; number_font_size=&#8221;120&#8243; symbol=&#8221;+&#8221; symbol_font_size=&#8221;40&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][milestone heading_inherit=&#8221;default&#8221; subject_padding=&#8221;2%&#8221; color=&#8221;Accent-Color&#8221; effect=&#8221;count&#8221; milestone_alignment=&#8221;default&#8221; number=&#8221;1&#8243; subject=&#8221;FAMILY BEHIND&#8221; number_font_size=&#8221;120&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#2D2D31&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;8%&#8221; top_margin=&#8221;10%&#8221; constrain_group_7=&#8221;yes&#8221; bottom_margin=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_ns010{background-color: #111111 !important;padding-top: 100px !important;padding-bottom: 100px !important;}&#8221; el_id=&#8221;que-hacemos&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column right_padding_desktop=&#8221;4%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong><span style=\"color: #fd7933; font-size: 16px;\">WHAT WE DO<\/span><\/strong>[\/vc_column_text][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Strategic vision. Actual execution. &#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]We combine strategic vision with operational execution. We don&#8217;t just launch projects\u2014we consolidate them and grow them sustainably.[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;40px&#8221;][nectar_cta btn_style=&#8221;curved-arrow-animation&#8221; heading_tag=&#8221;p&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; text_color=&#8221;#FFFFFF&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;Learn about the services&#8221;][\/vc_column][vc_column left_padding_desktop=&#8221;5%&#8221; top_padding_tablet=&#8221;5%&#8221; left_padding_tablet=&#8221;0&#8243; left_padding_phone=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#8D8D88&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1777279737941{margin-bottom: 0px !important;padding-bottom: 28px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"color: #e8673a;\"><strong>01<\/strong><\/p>\n<h3 style=\"padding-bottom: 20px; color: white;\">Operational infrastructure<\/h3>\n<p>Centralized strategy, finance, HR, legal, IT and executive management for our investee companies.[\/vc_column_text][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-2&#8243; animate=&#8221;yes&#8221;][vc_column_text css=&#8221;.vc_custom_1777280532524{margin-bottom: 0px !important;padding-top: 28px !important;padding-bottom: 28px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"color: #e8673a;\"><strong>02<\/strong><\/p>\n<h3 style=\"padding-bottom: 20px; color: white;\">Creation and operation<\/h3>\n<p>We work with external clients in hospitality, communications, concierge, and media \u2014 from concept to growth.[\/vc_column_text][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-2&#8243; animate=&#8221;yes&#8221;][vc_column_text css=&#8221;.vc_custom_1777280538081{margin-bottom: 0px !important;padding-top: 28px !important;padding-bottom: 28px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"color: #e8673a;\"><strong>03<\/strong><\/p>\n<h3 style=\"padding-bottom: 20px; color: white;\">Management training<\/h3>\n<p>Programs for junior profiles who are making the leap to roles of greater responsibility.[\/vc_column_text][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-2&#8243; animate=&#8221;yes&#8221;][vc_column_text css=&#8221;.vc_custom_1777280544619{margin-bottom: 0px !important;padding-top: 28px !important;padding-bottom: 28px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"color: #e8673a;\"><strong>04<\/strong><\/p>\n<h3 style=\"padding-bottom: 20px; color: white;\">Operational optimization<\/h3>\n<p>Analysis and redesign of internal systems to scale in an orderly and high-quality manner.[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"color: #ffffff;\">We combine strategic vision with operational execution. We don&#8217;t just launch projects\u2014we consolidate them and grow them sustainably. <\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_ns018{padding-top: 100px !important;padding-bottom: 20px !important;}&#8221; el_id=&#8221;portfolio&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong><span style=\"color: #fd7933; font-size: 16px;\">PORTFOLIO<\/span><\/strong>[\/vc_column_text][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;3%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Six companies. Two markets. &#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_cta btn_style=&#8221;curved-arrow-animation&#8221; heading_tag=&#8221;p&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; text_color=&#8221;#000000&#8243; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;right&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;Let&#039;s talk&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;even&#8221; responsive_display=&#8221;stacked&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;p&#8221; col_3_text_element=&#8221;p&#8221; cta_1_nofollow=&#8221;true&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;full_border&#8221; hover_color=&#8221;accent-color&#8221; border_radius=&#8221;15px&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;large&#8221; col_1_content=&#8221;Maneuvre Co.&#8221; col_2_content=&#8221;Public relations and communication&#8221; cta_1_text=&#8221;ES \/ NL&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;even&#8221; responsive_display=&#8221;stacked&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;p&#8221; col_3_text_element=&#8221;p&#8221; cta_1_nofollow=&#8221;true&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;full_border&#8221; hover_color=&#8221;accent-color&#8221; border_radius=&#8221;15px&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;large&#8221; col_1_content=&#8221;Gezelle&#8221; col_2_content=&#8221;Luxury hospitality consulting&#8221; cta_1_text=&#8221;NL&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;even&#8221; responsive_display=&#8221;stacked&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;p&#8221; col_3_text_element=&#8221;p&#8221; cta_1_nofollow=&#8221;true&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;full_border&#8221; hover_color=&#8221;accent-color&#8221; border_radius=&#8221;15px&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;large&#8221; col_1_content=&#8221;Curated ES&#8221; col_2_content=&#8221;Concierge and relocation in Valencia and the Balearic Islands&#8221; cta_1_text=&#8221;ES&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;even&#8221; responsive_display=&#8221;stacked&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;p&#8221; col_3_text_element=&#8221;p&#8221; cta_1_nofollow=&#8221;true&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;full_border&#8221; hover_color=&#8221;accent-color&#8221; border_radius=&#8221;15px&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;large&#8221; col_1_content=&#8221;Oso Izakaya&#8221; col_2_content=&#8221;Restauraci\u00f3n \u2014 opens in Pu\u00e7ol, 2026&#8243; cta_1_text=&#8221;ES&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;even&#8221; responsive_display=&#8221;stacked&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;p&#8221; col_3_text_element=&#8221;p&#8221; cta_1_nofollow=&#8221;true&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;full_border&#8221; hover_color=&#8221;accent-color&#8221; border_radius=&#8221;15px&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;large&#8221; col_1_content=&#8221;Nice Work&#8221; col_2_content=&#8221;Newsletter for entrepreneurs&#8221; cta_1_text=&#8221;ES \/ NL&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_horizontal_list_item columns=&#8221;3&#8243; column_layout_using_3_columns=&#8221;even&#8221; responsive_display=&#8221;stacked&#8221; col_1_text_align=&#8221;left&#8221; col_2_text_align=&#8221;left&#8221; col_3_text_align=&#8221;right&#8221; col_1_text_element=&#8221;h3&#8243; col_2_text_element=&#8221;p&#8221; col_3_text_element=&#8221;p&#8221; cta_1_nofollow=&#8221;true&#8221; font_family=&#8221;p&#8221; hover_effect=&#8221;full_border&#8221; hover_color=&#8221;accent-color&#8221; border_radius=&#8221;15px&#8221; icon_family=&#8221;none&#8221; icon_size=&#8221;large&#8221; col_1_content=&#8221;The Miniaturist&#8221; col_2_content=&#8221;Retail and specialized content&#8221; cta_1_text=&#8221;ES&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#F0552A&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; top_margin=&#8221;8%&#8221; bottom_margin=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;15px&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_ns027{background-color: #e8673a !important;padding-top: 80px !important;padding-bottom: 80px !important;border-radius: 16px !important;margin-left: 24px !important;margin-right: 24px !important;margin-bottom: 60px !important;}&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Do you have a project you want to build well?&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]We bring a practical and results-oriented approach, actively participating in all phases of the project.[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50px&#8221;][nectar_cta btn_style=&#8221;curved-arrow-animation&#8221; heading_tag=&#8221;p&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;white&#8221; text_color=&#8221;#000000&#8243; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;Let&#039;s talk&#8221; padding_top=&#8221;15px&#8221; padding_bottom=&#8221;15px&#8221; padding_left=&#8221;30px&#8221; padding_right=&#8221;30px&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-363","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/northsound.es\/en\/wp-json\/wp\/v2\/pages\/363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/northsound.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/northsound.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/northsound.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/northsound.es\/en\/wp-json\/wp\/v2\/comments?post=363"}],"version-history":[{"count":6,"href":"https:\/\/northsound.es\/en\/wp-json\/wp\/v2\/pages\/363\/revisions"}],"predecessor-version":[{"id":388,"href":"https:\/\/northsound.es\/en\/wp-json\/wp\/v2\/pages\/363\/revisions\/388"}],"wp:attachment":[{"href":"https:\/\/northsound.es\/en\/wp-json\/wp\/v2\/media?parent=363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}